{"id":2786,"date":"2025-07-23T21:03:31","date_gmt":"2025-07-24T03:03:31","guid":{"rendered":"https:\/\/dragonesfc.mx\/?p=2786"},"modified":"2025-07-23T21:03:31","modified_gmt":"2025-07-24T03:03:31","slug":"dragonas-oaxaca-copa-victoria-jornada3","status":"publish","type":"post","link":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/","title":{"rendered":"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo"},"content":{"rendered":"<p data-start=\"488\" data-end=\"778\"><strong data-start=\"488\" data-end=\"537\">Las Dragonas de Oaxaca en la Copa TDP Femenil<\/strong> siguen demostrando su fuerza y talento. En la jornada 3, el equipo femenil sum\u00f3 su segunda victoria consecutiva tras imponerse 2-0 a M\u00e4gos Uni\u00f3n Deportiva, con goles de Erandi y Isabella, consolid\u00e1ndose como uno de los favoritos del torneo.<\/p>\n<p data-start=\"780\" data-end=\"1069\">Con este triunfo, las rojinegras llegaron a seis puntos en el Grupo 2 y mantienen el invicto en su participaci\u00f3n nacional. Erandi, originaria de Pinotepa Nacional, fue la encargada de abrir el marcador, mientras que Isabella sell\u00f3 el resultado con una gran definici\u00f3n en el segundo tiempo.<\/p>\n<h4 data-start=\"1071\" data-end=\"1096\"><img decoding=\"async\" class=\"alignnone size-full wp-image-2787\" src=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg\" alt=\"\" width=\"1440\" height=\"1152\" srcset=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-177x142.jpg 177w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-200x160.jpg 200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-300x240.jpg 300w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-400x320.jpg 400w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-500x400.jpg 500w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-600x480.jpg 600w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-700x560.jpg 700w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-768x614.jpg 768w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-800x640.jpg 800w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-1024x819.jpg 1024w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n-1200x960.jpg 1200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg 1440w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\ud83d\udcca <strong data-start=\"1219\" data-end=\"1239\">Resultado final:<\/strong><\/h4>\n<p data-start=\"1240\" data-end=\"1294\"><strong data-start=\"1240\" data-end=\"1294\">Dragonas de Oaxaca \ud83d\udc32 2-0 \ud83e\uddd9 M\u00e4gos Uni\u00f3n Deportiva<\/strong><\/p>\n<p data-start=\"1240\" data-end=\"1294\"><img decoding=\"async\" class=\"alignnone size-full wp-image-2788\" src=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n.jpg\" alt=\"\" width=\"1440\" height=\"1800\" srcset=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-200x250.jpg 200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-240x300.jpg 240w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-400x500.jpg 400w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-500x625.jpg 500w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-600x750.jpg 600w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-700x875.jpg 700w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-768x960.jpg 768w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-800x1000.jpg 800w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-819x1024.jpg 819w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-1200x1500.jpg 1200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n-1229x1536.jpg 1229w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/523793834_122216132024101329_8620359747465322395_n.jpg 1440w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/p>\n<h4 data-start=\"1296\" data-end=\"1317\">\ud83d\udd25 Pr\u00f3ximo reto:<\/h4>\n<p data-start=\"1318\" data-end=\"1488\">Las Dragonas enfrentar\u00e1n este jueves a <strong data-start=\"1357\" data-end=\"1392\">Club Deportivo San Juan del R\u00edo<\/strong>, buscando cerrar la fase de grupos con marca perfecta. El partido se disputar\u00e1 a las 09:00 hrs.<\/p>\n<p data-start=\"1490\" data-end=\"1601\">\n","protected":false},"excerpt":{"rendered":"<p>Las Dragonas de Oaxaca en la Copa TDP Femenil siguen  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[260],"tags":[],"class_list":["post-2786","post","type-post","status-publish","format-standard","hentry","category-dragonas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo - Tienda Dragones<\/title>\n<meta name=\"description\" content=\"Dragonas de Oaxaca en la Copa TDP Femenil logran su segunda victoria con goles de Erandi y Isabella. Las rojinegras van con todo rumbo a la siguiente fase.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo - Tienda Dragones\" \/>\n<meta property=\"og:description\" content=\"Dragonas de Oaxaca en la Copa TDP Femenil logran su segunda victoria con goles de Erandi y Isabella. Las rojinegras van con todo rumbo a la siguiente fase.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/\" \/>\n<meta property=\"og:site_name\" content=\"Tienda Dragones\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-24T03:03:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Reyes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@avivian_a@hotmail.com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Reyes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/\"},\"author\":{\"name\":\"Diego Reyes\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\"},\"headline\":\"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo\",\"datePublished\":\"2025-07-24T03:03:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/\"},\"wordCount\":154,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/522810175_122216102456101329_1738366912479579582_n.jpg\",\"articleSection\":[\"Dragonas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/\",\"name\":\"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo - Tienda Dragones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/522810175_122216102456101329_1738366912479579582_n.jpg\",\"datePublished\":\"2025-07-24T03:03:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\"},\"description\":\"Dragonas de Oaxaca en la Copa TDP Femenil logran su segunda victoria con goles de Erandi y Isabella. Las rojinegras van con todo rumbo a la siguiente fase.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/522810175_122216102456101329_1738366912479579582_n.jpg\",\"contentUrl\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/522810175_122216102456101329_1738366912479579582_n.jpg\",\"width\":1440,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/07\\\/23\\\/dragonas-oaxaca-copa-victoria-jornada3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dragonesfc.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#website\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/\",\"name\":\"Tienda Dragones\",\"description\":\"Instituci\u00f3n oaxaque\u00f1a dedicada a la ense\u00f1anza del futbol. Fundada en 2018, esta organizaci\u00f3n cuenta con 2 equipos en la Tercera Divisi\u00f3n Profesional de la Federaci\u00f3n Mexicana de Futbol, adem\u00e1s de seis academias en Tlalixtac, Zimatl\u00e1n, Cuilapam, Ocotl\u00e1n, Tamazulapam y Huatulco.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dragonesfc.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\",\"name\":\"Diego Reyes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"caption\":\"Diego Reyes\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/avivian_a@hotmail.com\"],\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/author\\\/diego-reyes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo - Tienda Dragones","description":"Dragonas de Oaxaca en la Copa TDP Femenil logran su segunda victoria con goles de Erandi y Isabella. Las rojinegras van con todo rumbo a la siguiente fase.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/","og_locale":"es_MX","og_type":"article","og_title":"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo - Tienda Dragones","og_description":"Dragonas de Oaxaca en la Copa TDP Femenil logran su segunda victoria con goles de Erandi y Isabella. Las rojinegras van con todo rumbo a la siguiente fase.","og_url":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/","og_site_name":"Tienda Dragones","article_published_time":"2025-07-24T03:03:31+00:00","og_image":[{"width":1440,"height":1152,"url":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg","type":"image\/jpeg"}],"author":"Diego Reyes","twitter_card":"summary_large_image","twitter_creator":"@avivian_a@hotmail.com","twitter_misc":{"Escrito por":"Diego Reyes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#article","isPartOf":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/"},"author":{"name":"Diego Reyes","@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30"},"headline":"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo","datePublished":"2025-07-24T03:03:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/"},"wordCount":154,"commentCount":0,"image":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#primaryimage"},"thumbnailUrl":"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg","articleSection":["Dragonas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/","url":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/","name":"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo - Tienda Dragones","isPartOf":{"@id":"https:\/\/dragonesfc.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#primaryimage"},"image":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#primaryimage"},"thumbnailUrl":"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg","datePublished":"2025-07-24T03:03:31+00:00","author":{"@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30"},"description":"Dragonas de Oaxaca en la Copa TDP Femenil logran su segunda victoria con goles de Erandi y Isabella. Las rojinegras van con todo rumbo a la siguiente fase.","breadcrumb":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#primaryimage","url":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg","contentUrl":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/07\/522810175_122216102456101329_1738366912479579582_n.jpg","width":1440,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/07\/23\/dragonas-oaxaca-copa-victoria-jornada3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dragonesfc.mx\/"},{"@type":"ListItem","position":2,"name":"Dragonas de Oaxaca en la Copa TDP Femenil: segunda victoria al hilo"}]},{"@type":"WebSite","@id":"https:\/\/dragonesfc.mx\/#website","url":"https:\/\/dragonesfc.mx\/","name":"Tienda Dragones","description":"Instituci\u00f3n oaxaque\u00f1a dedicada a la ense\u00f1anza del futbol. Fundada en 2018, esta organizaci\u00f3n cuenta con 2 equipos en la Tercera Divisi\u00f3n Profesional de la Federaci\u00f3n Mexicana de Futbol, adem\u00e1s de seis academias en Tlalixtac, Zimatl\u00e1n, Cuilapam, Ocotl\u00e1n, Tamazulapam y Huatulco.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dragonesfc.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30","name":"Diego Reyes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","caption":"Diego Reyes"},"sameAs":["https:\/\/x.com\/avivian_a@hotmail.com"],"url":"https:\/\/dragonesfc.mx\/index.php\/author\/diego-reyes\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/2786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2786"}],"version-history":[{"count":1,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/2786\/revisions"}],"predecessor-version":[{"id":2790,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/2786\/revisions\/2790"}],"wp:attachment":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}