{"id":3104,"date":"2025-12-01T12:45:04","date_gmt":"2025-12-01T18:45:04","guid":{"rendered":"https:\/\/dragonesfc.mx\/?p=3104"},"modified":"2025-12-01T12:45:04","modified_gmt":"2025-12-01T18:45:04","slug":"bajas-jugadores-dragones-2025-2026","status":"publish","type":"post","link":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/","title":{"rendered":"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial"},"content":{"rendered":"<p data-start=\"334\" data-end=\"672\">El Club Dragones de Oaxaca informa a toda nuestra afici\u00f3n las bajas oficiales de los jugadores <strong data-start=\"429\" data-end=\"448\">Daniel Gonz\u00e1lez<\/strong>, <strong data-start=\"450\" data-end=\"469\">Edgard Quintero<\/strong>, <strong data-start=\"471\" data-end=\"488\">Jos\u00e9 Quintero<\/strong>, <strong data-start=\"490\" data-end=\"507\">Abraham P\u00e9rez<\/strong>, <strong data-start=\"509\" data-end=\"525\">Mauro Kotaro<\/strong> y <strong data-start=\"528\" data-end=\"544\">Jes\u00fas Ancona<\/strong>, quienes no continuar\u00e1n con nuestro equipo para la segunda vuelta de la Temporada <strong data-start=\"627\" data-end=\"640\">2025\u20132026<\/strong> de la <strong data-start=\"647\" data-end=\"671\">Liga Premier Serie B<\/strong>.<\/p>\n<p data-start=\"334\" data-end=\"672\"><img decoding=\"async\" class=\"alignnone  wp-image-3105\" src=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg\" alt=\"\" width=\"425\" height=\"531\" srcset=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-200x250.jpg 200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-240x300.jpg 240w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-400x500.jpg 400w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-500x625.jpg 500w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-600x750.jpg 600w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-700x875.jpg 700w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-768x960.jpg 768w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-800x1000.jpg 800w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n-819x1024.jpg 819w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg 1080w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/> <img decoding=\"async\" class=\"alignnone  wp-image-3106\" src=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n.jpg\" alt=\"\" width=\"416\" height=\"520\" srcset=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-200x250.jpg 200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-240x300.jpg 240w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-400x500.jpg 400w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-500x625.jpg 500w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-600x750.jpg 600w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-700x875.jpg 700w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-768x960.jpg 768w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-800x1000.jpg 800w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n-819x1024.jpg 819w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583859668_18072211505362324_6080903856323702027_n.jpg 1080w\" sizes=\"(max-width: 416px) 100vw, 416px\" \/><\/p>\n<p data-start=\"674\" data-end=\"975\">A cada uno de ellos, expresamos nuestro agradecimiento profundo por defender nuestros colores con entrega, disciplina y profesionalismo. Su trabajo dentro y fuera de la cancha form\u00f3 parte importante de esta etapa en la historia del club, contribuyendo al crecimiento competitivo del proyecto Dragones.<\/p>\n<p data-start=\"977\" data-end=\"1225\">Sabemos que el futbol est\u00e1 hecho de ciclos, y cada paso abre un nuevo camino. Les deseamos \u00e9xito en los proyectos que emprendan a partir de hoy, seguros de que seguir\u00e1n avanzando con la misma pasi\u00f3n que mostraron mientras portaron nuestra camiseta.<\/p>\n<p data-start=\"1227\" data-end=\"1342\"><strong data-start=\"1227\" data-end=\"1262\">Una vez Drag\u00f3n\u2026 siempre Drag\u00f3n.<\/strong><br data-start=\"1262\" data-end=\"1265\" \/>El Club Dragones de Oaxaca les reconoce y les desea lo mejor en lo que viene.<\/p>\n<p data-start=\"1344\" data-end=\"1365\">#ConquistaLaTradici\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Club Dragones de Oaxaca informa a toda nuestra afici\u00f3n  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[261],"tags":[],"class_list":["post-3104","post","type-post","status-publish","format-standard","hentry","category-dragones-premier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial - Tienda Dragones<\/title>\n<meta name=\"description\" content=\"Dragones anuncia las bajas de seis jugadores para la segunda vuelta 2025\u20132026. Agradecimiento, reconocimiento y cierre de ciclo en la Liga Premier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial - Tienda Dragones\" \/>\n<meta property=\"og:description\" content=\"Dragones anuncia las bajas de seis jugadores para la segunda vuelta 2025\u20132026. Agradecimiento, reconocimiento y cierre de ciclo en la Liga Premier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Tienda Dragones\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T18:45:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Reyes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@avivian_a@hotmail.com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Reyes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/\"},\"author\":{\"name\":\"Diego Reyes\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\"},\"headline\":\"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial\",\"datePublished\":\"2025-12-01T18:45:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/\"},\"wordCount\":173,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/583139793_18072211514362324_5204987608002018878_n.jpg\",\"articleSection\":[\"Dragones Premier\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/\",\"name\":\"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial - Tienda Dragones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/583139793_18072211514362324_5204987608002018878_n.jpg\",\"datePublished\":\"2025-12-01T18:45:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\"},\"description\":\"Dragones anuncia las bajas de seis jugadores para la segunda vuelta 2025\u20132026. Agradecimiento, reconocimiento y cierre de ciclo en la Liga Premier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/583139793_18072211514362324_5204987608002018878_n.jpg\",\"contentUrl\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/583139793_18072211514362324_5204987608002018878_n.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2025\\\/12\\\/01\\\/bajas-jugadores-dragones-2025-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dragonesfc.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#website\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/\",\"name\":\"Tienda Dragones\",\"description\":\"Instituci\u00f3n oaxaque\u00f1a dedicada a la ense\u00f1anza del futbol. Fundada en 2018, esta organizaci\u00f3n cuenta con 2 equipos en la Tercera Divisi\u00f3n Profesional de la Federaci\u00f3n Mexicana de Futbol, adem\u00e1s de seis academias en Tlalixtac, Zimatl\u00e1n, Cuilapam, Ocotl\u00e1n, Tamazulapam y Huatulco.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dragonesfc.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\",\"name\":\"Diego Reyes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"caption\":\"Diego Reyes\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/avivian_a@hotmail.com\"],\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/author\\\/diego-reyes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial - Tienda Dragones","description":"Dragones anuncia las bajas de seis jugadores para la segunda vuelta 2025\u20132026. Agradecimiento, reconocimiento y cierre de ciclo en la Liga Premier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/","og_locale":"es_MX","og_type":"article","og_title":"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial - Tienda Dragones","og_description":"Dragones anuncia las bajas de seis jugadores para la segunda vuelta 2025\u20132026. Agradecimiento, reconocimiento y cierre de ciclo en la Liga Premier.","og_url":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/","og_site_name":"Tienda Dragones","article_published_time":"2025-12-01T18:45:04+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg","type":"image\/jpeg"}],"author":"Diego Reyes","twitter_card":"summary_large_image","twitter_creator":"@avivian_a@hotmail.com","twitter_misc":{"Escrito por":"Diego Reyes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#article","isPartOf":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/"},"author":{"name":"Diego Reyes","@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30"},"headline":"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial","datePublished":"2025-12-01T18:45:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/"},"wordCount":173,"commentCount":0,"image":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#primaryimage"},"thumbnailUrl":"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg","articleSection":["Dragones Premier"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/","url":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/","name":"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial - Tienda Dragones","isPartOf":{"@id":"https:\/\/dragonesfc.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#primaryimage"},"image":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#primaryimage"},"thumbnailUrl":"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg","datePublished":"2025-12-01T18:45:04+00:00","author":{"@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30"},"description":"Dragones anuncia las bajas de seis jugadores para la segunda vuelta 2025\u20132026. Agradecimiento, reconocimiento y cierre de ciclo en la Liga Premier.","breadcrumb":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#primaryimage","url":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg","contentUrl":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2025\/12\/583139793_18072211514362324_5204987608002018878_n.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/dragonesfc.mx\/index.php\/2025\/12\/01\/bajas-jugadores-dragones-2025-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dragonesfc.mx\/"},{"@type":"ListItem","position":2,"name":"Bajas de jugadores Dragones 2025-2026 | Anuncio Oficial"}]},{"@type":"WebSite","@id":"https:\/\/dragonesfc.mx\/#website","url":"https:\/\/dragonesfc.mx\/","name":"Tienda Dragones","description":"Instituci\u00f3n oaxaque\u00f1a dedicada a la ense\u00f1anza del futbol. Fundada en 2018, esta organizaci\u00f3n cuenta con 2 equipos en la Tercera Divisi\u00f3n Profesional de la Federaci\u00f3n Mexicana de Futbol, adem\u00e1s de seis academias en Tlalixtac, Zimatl\u00e1n, Cuilapam, Ocotl\u00e1n, Tamazulapam y Huatulco.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dragonesfc.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30","name":"Diego Reyes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","caption":"Diego Reyes"},"sameAs":["https:\/\/x.com\/avivian_a@hotmail.com"],"url":"https:\/\/dragonesfc.mx\/index.php\/author\/diego-reyes\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/3104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3104"}],"version-history":[{"count":1,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/3104\/revisions"}],"predecessor-version":[{"id":3107,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/3104\/revisions\/3107"}],"wp:attachment":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}