{"id":3285,"date":"2026-02-07T10:43:52","date_gmt":"2026-02-07T16:43:52","guid":{"rendered":"https:\/\/dragonesfc.mx\/?p=3285"},"modified":"2026-02-07T10:43:52","modified_gmt":"2026-02-07T16:43:52","slug":"dragones-cae-ante-fc-racing-despide-copa-conecta-2026","status":"publish","type":"post","link":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/","title":{"rendered":"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><b>Dragones cae ante FC Racing<\/b><\/span> y se despide de la <span class=\"s1\"><b>Copa Conecta 2026<\/b><\/span> tras perder <span class=\"s1\"><b>3-1<\/b><\/span> en la <span class=\"s1\"><b>Unidad Deportiva Hugo S\u00e1nchez<\/b><\/span>, en Boca del R\u00edo, Veracruz, dentro de la <span class=\"s1\"><b>Etapa 2<\/b><\/span> del certamen.<\/p>\n<p class=\"p1\">El equipo de <span class=\"s1\"><b>Dragones de Oaxaca<\/b><\/span> enfrent\u00f3 a <span class=\"s1\"><b>Racing F\u00fatbol Club<\/b><\/span> en un duelo intenso, donde los detalles a bal\u00f3n parado marcaron la diferencia a favor del conjunto local. Durante la primera mitad, el encuentro se mantuvo equilibrado hasta que Racing logr\u00f3 abrir el marcador al <span class=\"s1\"><b>minuto 45+1<\/b><\/span>, tras una jugada de t\u00e1ctica fija.<\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-3286\" src=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg\" alt=\"\" width=\"602\" height=\"753\" srcset=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-200x250.jpeg 200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-240x300.jpeg 240w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-400x500.jpeg 400w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-500x625.jpeg 500w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-600x750.jpeg 600w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-700x875.jpeg 700w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-768x960.jpeg 768w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-800x1000.jpeg 800w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-819x1024.jpeg 819w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-1200x1500.jpeg 1200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-1229x1536.jpeg 1229w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-1638x2048.jpeg 1638w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg 2048w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/p>\n<p class=\"p1\">Para la parte complementaria, <span class=\"s1\"><b>Dragones cae ante FC Racing<\/b><\/span> pese a los ajustes realizados por el cuerpo t\u00e9cnico encabezado por <span class=\"s1\"><b>Jes\u00fas Garc\u00eda Avelino<\/b><\/span>, en busca de igualar el marcador. Sin embargo, nuevamente a bal\u00f3n parado, el conjunto veracruzano ampli\u00f3 la ventaja al <span class=\"s1\"><b>minuto 75<\/b><\/span>, colocando el <span class=\"s1\"><b>2-0<\/b><\/span>.<\/p>\n<p class=\"p1\">En los minutos finales, al <span class=\"s1\"><b>85\u2019<\/b><\/span>, Racing convirti\u00f3 el tercer tanto del partido desde el manch\u00f3n penal. A pesar del marcador adverso, Dragones mantuvo la intensidad hasta el final y logr\u00f3 el descuento al <span class=\"s1\"><b>minuto 89<\/b><\/span>, cuando <span class=\"s1\"><b>Ismael Soloache<\/b><\/span> envi\u00f3 un centro preciso que <span class=\"s1\"><b>Alejandro Romero<\/b><\/span> remat\u00f3 de cabeza para marcar el <span class=\"s1\"><b>3-1 definitivo<\/b><\/span>.<\/p>\n<p class=\"p1\">Con este resultado, <span class=\"s1\"><b>Dragones cae ante FC Racing<\/b><\/span> y concluye su <span class=\"s1\"><b>segunda participaci\u00f3n en la Copa Conecta 2026<\/b><\/span>, cerrando una etapa que sirvi\u00f3 como experiencia competitiva y crecimiento para el plantel rojinegro.<\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-3287\" src=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-scaled.jpeg\" alt=\"\" width=\"601\" height=\"751\" srcset=\"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-200x250.jpeg 200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-240x300.jpeg 240w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-400x500.jpeg 400w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-500x625.jpeg 500w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-600x750.jpeg 600w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-700x875.jpeg 700w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-768x960.jpeg 768w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-800x1000.jpeg 800w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-819x1024.jpeg 819w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1200x1500.jpeg 1200w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1229x1536.jpeg 1229w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1638x2048.jpeg 1638w, https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-scaled.jpeg 2048w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/><\/p>\n<p class=\"p1\">Sin tiempo para lamentos, el equipo oaxaque\u00f1o enfocar\u00e1 de inmediato su preparaci\u00f3n en la <span class=\"s1\"><b>Liga Premier Serie B<\/b><\/span>. Dragones viajar\u00e1 esta misma noche al <span class=\"s1\"><b>Estado de M\u00e9xico<\/b><\/span> para enfrentar a <span class=\"s1\"><b>Artesanos de Metepec<\/b><\/span> en la <span class=\"s1\"><b>Jornada 14<\/b><\/span>, encuentro programado para este <span class=\"s1\"><b>s\u00e1bado 7 de febrero a las 16:00 horas<\/b><\/span>, en la <span class=\"s1\"><b>Unidad Deportiva Alarc\u00f3n Hisojo<\/b><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dragones cae ante FC Racing y se despide de la  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":3286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[261],"tags":[],"class_list":["post-3285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dragones-premier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dragones cae ante FC Racing y se despide de la Copa Conecta 2026 - Tienda Dragones<\/title>\n<meta name=\"description\" content=\"Dragones cae ante FC Racing 3-1 en la Etapa 2 de la Copa Conecta 2026 y ahora se enfoca en la Jornada 14 de la Liga Premier Serie B.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026 - Tienda Dragones\" \/>\n<meta property=\"og:description\" content=\"Dragones cae ante FC Racing 3-1 en la Etapa 2 de la Copa Conecta 2026 y ahora se enfoca en la Jornada 14 de la Liga Premier Serie B.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Tienda Dragones\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T16:43:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Reyes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@avivian_a@hotmail.com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Reyes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/\"},\"author\":{\"name\":\"Diego Reyes\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\"},\"headline\":\"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026\",\"datePublished\":\"2026-02-07T16:43:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/\"},\"wordCount\":294,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg\",\"articleSection\":[\"Dragones Premier\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/\",\"name\":\"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026 - Tienda Dragones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg\",\"datePublished\":\"2026-02-07T16:43:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\"},\"description\":\"Dragones cae ante FC Racing 3-1 en la Etapa 2 de la Copa Conecta 2026 y ahora se enfoca en la Jornada 14 de la Liga Premier Serie B.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/dragonesfc.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg\",\"width\":2048,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/2026\\\/02\\\/07\\\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dragonesfc.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#website\",\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/\",\"name\":\"Tienda Dragones\",\"description\":\"Instituci\u00f3n oaxaque\u00f1a dedicada a la ense\u00f1anza del futbol. Fundada en 2018, esta organizaci\u00f3n cuenta con 2 equipos en la Tercera Divisi\u00f3n Profesional de la Federaci\u00f3n Mexicana de Futbol, adem\u00e1s de seis academias en Tlalixtac, Zimatl\u00e1n, Cuilapam, Ocotl\u00e1n, Tamazulapam y Huatulco.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dragonesfc.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dragonesfc.mx\\\/#\\\/schema\\\/person\\\/6efb1581b5a41666a33c988ce03b7e30\",\"name\":\"Diego Reyes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g\",\"caption\":\"Diego Reyes\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/avivian_a@hotmail.com\"],\"url\":\"https:\\\/\\\/dragonesfc.mx\\\/index.php\\\/author\\\/diego-reyes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026 - Tienda Dragones","description":"Dragones cae ante FC Racing 3-1 en la Etapa 2 de la Copa Conecta 2026 y ahora se enfoca en la Jornada 14 de la Liga Premier Serie B.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/","og_locale":"es_MX","og_type":"article","og_title":"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026 - Tienda Dragones","og_description":"Dragones cae ante FC Racing 3-1 en la Etapa 2 de la Copa Conecta 2026 y ahora se enfoca en la Jornada 14 de la Liga Premier Serie B.","og_url":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/","og_site_name":"Tienda Dragones","article_published_time":"2026-02-07T16:43:52+00:00","og_image":[{"width":2048,"height":2560,"url":"http:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg","type":"image\/jpeg"}],"author":"Diego Reyes","twitter_card":"summary_large_image","twitter_creator":"@avivian_a@hotmail.com","twitter_misc":{"Escrito por":"Diego Reyes","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#article","isPartOf":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/"},"author":{"name":"Diego Reyes","@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30"},"headline":"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026","datePublished":"2026-02-07T16:43:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/"},"wordCount":294,"commentCount":0,"image":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg","articleSection":["Dragones Premier"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/","url":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/","name":"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026 - Tienda Dragones","isPartOf":{"@id":"https:\/\/dragonesfc.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#primaryimage"},"image":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg","datePublished":"2026-02-07T16:43:52+00:00","author":{"@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30"},"description":"Dragones cae ante FC Racing 3-1 en la Etapa 2 de la Copa Conecta 2026 y ahora se enfoca en la Jornada 14 de la Liga Premier Serie B.","breadcrumb":{"@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#primaryimage","url":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg","contentUrl":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg","width":2048,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/dragonesfc.mx\/index.php\/2026\/02\/07\/dragones-cae-ante-fc-racing-despide-copa-conecta-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dragonesfc.mx\/"},{"@type":"ListItem","position":2,"name":"Dragones cae ante FC Racing y se despide de la Copa Conecta 2026"}]},{"@type":"WebSite","@id":"https:\/\/dragonesfc.mx\/#website","url":"https:\/\/dragonesfc.mx\/","name":"Tienda Dragones","description":"Instituci\u00f3n oaxaque\u00f1a dedicada a la ense\u00f1anza del futbol. Fundada en 2018, esta organizaci\u00f3n cuenta con 2 equipos en la Tercera Divisi\u00f3n Profesional de la Federaci\u00f3n Mexicana de Futbol, adem\u00e1s de seis academias en Tlalixtac, Zimatl\u00e1n, Cuilapam, Ocotl\u00e1n, Tamazulapam y Huatulco.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dragonesfc.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dragonesfc.mx\/#\/schema\/person\/6efb1581b5a41666a33c988ce03b7e30","name":"Diego Reyes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b0dc02e0e78048e108aaf3f3e856759def5a4ce1b33ebfc1eb9d70ad5ab71137?s=96&d=mm&r=g","caption":"Diego Reyes"},"sameAs":["https:\/\/x.com\/avivian_a@hotmail.com"],"url":"https:\/\/dragonesfc.mx\/index.php\/author\/diego-reyes\/"}]}},"jetpack_featured_media_url":"https:\/\/dragonesfc.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-04-at-23.26.17-1-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/3285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3285"}],"version-history":[{"count":1,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/3285\/revisions"}],"predecessor-version":[{"id":3288,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/posts\/3285\/revisions\/3288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/media\/3286"}],"wp:attachment":[{"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dragonesfc.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}